{"id":355,"count":1,"description":"","link":"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/","name":"Destiler\u00eda Santa Luc\u00eda","slug":"destileria-santa-lucia","taxonomy":"product_brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destiler\u00eda Santa Luc\u00eda archivos - Agaveros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destiler\u00eda Santa Luc\u00eda archivos - Agaveros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/\" \/>\n<meta property=\"og:site_name\" content=\"Agaveros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/index.php\\\/brands\\\/destileria-santa-lucia\\\/\",\"url\":\"https:\\\/\\\/www.agaveros.com\\\/index.php\\\/brands\\\/destileria-santa-lucia\\\/\",\"name\":\"Destiler\u00eda Santa Luc\u00eda archivos - Agaveros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/index.php\\\/brands\\\/destileria-santa-lucia\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/index.php\\\/brands\\\/destileria-santa-lucia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.agaveros.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destiler\u00eda Santa Luc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/#website\",\"url\":\"https:\\\/\\\/www.agaveros.com\\\/\",\"name\":\"Agaveros\",\"description\":\"- Tienda de Mezcales y Tequilas -\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.agaveros.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/#organization\",\"name\":\"Agaveros\",\"url\":\"https:\\\/\\\/www.agaveros.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.agaveros.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-agaveros-2022-transp.png\",\"contentUrl\":\"https:\\\/\\\/www.agaveros.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-agaveros-2022-transp.png\",\"width\":1000,\"height\":358,\"caption\":\"Agaveros\"},\"image\":{\"@id\":\"https:\\\/\\\/www.agaveros.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destiler\u00eda Santa Luc\u00eda archivos - Agaveros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/","og_locale":"es_ES","og_type":"article","og_title":"Destiler\u00eda Santa Luc\u00eda archivos - Agaveros","og_url":"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/","og_site_name":"Agaveros","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/","url":"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/","name":"Destiler\u00eda Santa Luc\u00eda archivos - Agaveros","isPartOf":{"@id":"https:\/\/www.agaveros.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.agaveros.com\/index.php\/brands\/destileria-santa-lucia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.agaveros.com\/"},{"@type":"ListItem","position":2,"name":"Destiler\u00eda Santa Luc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.agaveros.com\/#website","url":"https:\/\/www.agaveros.com\/","name":"Agaveros","description":"- Tienda de Mezcales y Tequilas -","publisher":{"@id":"https:\/\/www.agaveros.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.agaveros.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.agaveros.com\/#organization","name":"Agaveros","url":"https:\/\/www.agaveros.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.agaveros.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.agaveros.com\/wp-content\/uploads\/2022\/07\/logo-agaveros-2022-transp.png","contentUrl":"https:\/\/www.agaveros.com\/wp-content\/uploads\/2022\/07\/logo-agaveros-2022-transp.png","width":1000,"height":358,"caption":"Agaveros"},"image":{"@id":"https:\/\/www.agaveros.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.agaveros.com\/index.php\/wp-json\/wp\/v2\/product_brand\/355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agaveros.com\/index.php\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/www.agaveros.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/www.agaveros.com\/index.php\/wp-json\/wp\/v2\/product?product_brand=355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}